{"id":35234,"date":"2026-01-02T13:58:27","date_gmt":"2026-01-02T12:58:27","guid":{"rendered":"https:\/\/eyelaser.ch\/laser-eye-surgery\/smartsight-nova-zuerich-praezision\/"},"modified":"2026-04-28T19:23:04","modified_gmt":"2026-04-28T17:23:04","slug":"smartsight-nova-zuerich-praezision","status":"publish","type":"page","link":"https:\/\/eyelaser.ch\/en\/laser-eye-surgery\/smartsight-nova-precision-in-zurich\/","title":{"rendered":"SmartSight Nova in Zurich: Maximum Precision through Pioneering Centering"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":33960,"parent":19702,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-flexible-content.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-35234","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/pages\/35234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/comments?post=35234"}],"version-history":[{"count":0,"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/pages\/35234\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/pages\/19702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/media\/33960"}],"wp:attachment":[{"href":"https:\/\/eyelaser.ch\/en\/wp-json\/wp\/v2\/media?parent=35234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}